{"id":915,"date":"2024-06-11T23:42:45","date_gmt":"2024-06-11T21:42:45","guid":{"rendered":"https:\/\/zeutheneryachtclub.de\/2021\/?p=915"},"modified":"2024-06-12T08:02:52","modified_gmt":"2024-06-12T06:02:52","slug":"willkommen-zur-zeuthener-woche-2024-im-zyc","status":"publish","type":"post","link":"https:\/\/zeutheneryachtclub.de\/2021\/2024\/06\/11\/willkommen-zur-zeuthener-woche-2024-im-zyc\/","title":{"rendered":"Willkommen zur Zeuthener Woche 2024 im ZYC"},"content":{"rendered":"\n<p>Wir freuen uns auf alle Teilnehmerinnen und Teilnehmer an den Regatten der Zeuthener Woche 2024 am 6. und 7. Juli sowie auf alle G\u00e4ste im Zeuthener Yachtclub e.V.<\/p>\n\n\n\n<p>Im Bereich &#8222;Regatta&#8220; findet Ihr die Ausschreibung sowie den Link zu <a href=\"https:\/\/www.manage2sail.com\/de-DE\/event\/ZW2024#!\/\" target=\"_blank\" rel=\"noreferrer noopener\">manage2sail<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/zeutheneryachtclub.de\/2021\/wp-content\/uploads\/2024\/06\/Plakat_Zeuthener_Woche_2024-724x1024.jpg\" alt=\"\" class=\"wp-image-917\" srcset=\"https:\/\/zeutheneryachtclub.de\/2021\/wp-content\/uploads\/2024\/06\/Plakat_Zeuthener_Woche_2024-724x1024.jpg 724w, https:\/\/zeutheneryachtclub.de\/2021\/wp-content\/uploads\/2024\/06\/Plakat_Zeuthener_Woche_2024-212x300.jpg 212w, https:\/\/zeutheneryachtclub.de\/2021\/wp-content\/uploads\/2024\/06\/Plakat_Zeuthener_Woche_2024-768x1086.jpg 768w, https:\/\/zeutheneryachtclub.de\/2021\/wp-content\/uploads\/2024\/06\/Plakat_Zeuthener_Woche_2024-1086x1536.jpg 1086w, https:\/\/zeutheneryachtclub.de\/2021\/wp-content\/uploads\/2024\/06\/Plakat_Zeuthener_Woche_2024-1448x2048.jpg 1448w, https:\/\/zeutheneryachtclub.de\/2021\/wp-content\/uploads\/2024\/06\/Plakat_Zeuthener_Woche_2024-scaled.jpg 1810w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Wir freuen uns auf alle Teilnehmerinnen und Teilnehmer an den Regatten der Zeuthener Woche 2024 am 6. und 7. Juli sowie auf alle G\u00e4ste im Zeuthener Yachtclub e.V. Im Bereich &#8222;Regatta&#8220; findet Ihr die Ausschreibung<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[],"class_list":["post-915","post","type-post","status-publish","format-standard","hentry","category-vereinsnachrichten"],"_links":{"self":[{"href":"https:\/\/zeutheneryachtclub.de\/2021\/wp-json\/wp\/v2\/posts\/915","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zeutheneryachtclub.de\/2021\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/zeutheneryachtclub.de\/2021\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/zeutheneryachtclub.de\/2021\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/zeutheneryachtclub.de\/2021\/wp-json\/wp\/v2\/comments?post=915"}],"version-history":[{"count":2,"href":"https:\/\/zeutheneryachtclub.de\/2021\/wp-json\/wp\/v2\/posts\/915\/revisions"}],"predecessor-version":[{"id":920,"href":"https:\/\/zeutheneryachtclub.de\/2021\/wp-json\/wp\/v2\/posts\/915\/revisions\/920"}],"wp:attachment":[{"href":"https:\/\/zeutheneryachtclub.de\/2021\/wp-json\/wp\/v2\/media?parent=915"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zeutheneryachtclub.de\/2021\/wp-json\/wp\/v2\/categories?post=915"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zeutheneryachtclub.de\/2021\/wp-json\/wp\/v2\/tags?post=915"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}